{"id":683536,"date":"2026-04-04T17:48:21","date_gmt":"2026-04-04T17:48:21","guid":{"rendered":"https:\/\/truckbrasil.net\/wp\/truck\/2026\/04\/04\/soquete-de-impacto-sextavado-de-34-pol-com-encaixe-de-34-pol-gedore-20051-42224528052-2\/"},"modified":"2026-04-04T17:48:21","modified_gmt":"2026-04-04T17:48:21","slug":"soquete-de-impacto-sextavado-de-34-pol-com-encaixe-de-34-pol-gedore-20051-42224528052-2","status":"publish","type":"post","link":"https:\/\/truckbrasil.net\/wp\/truck\/2026\/04\/04\/soquete-de-impacto-sextavado-de-34-pol-com-encaixe-de-34-pol-gedore-20051-42224528052-2\/","title":{"rendered":"Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051 &#8211; 42224528052"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051 no dia da inclus\u00e3o deste produto era de <strong>R$ 108.90<\/strong>.<\/h3>\n<p><\/p>\n<p>Acesse a loja e veja se o pre\u00e7o ou estoque mudaram: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42224528052&#038;a=690303&#038;m=118895\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1\" alt=\"Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051\" \/> &#8211; Loja do Mecanico BR<\/a><\/p>\n<p>Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051<\/p>\n<h5>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h5>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; Clique <\/a>.<\/p>\n<hr \/>\n<hr \/>\n<h4>A loja Ferramentas Kennedy oferece a possibilidade de busca mais ampla para <a href=\"https:\/\/www.ferramentaskennedy.com.br\/busca?q=Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051&#038;utm_campaign=ecompare&#038;utm_medium=maisplataforma&#038;utm_source=mais\" target=\"_blank\" rel=\"noopener\">Soquete de Impacto Sextavado de 34 Pol com Encaixe de 34 Pol GEDORE-20051, clique e continue <strong>pesquisando&#8230;<\/strong><\/h4>\n<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1\" alt=\"Pesquise na Ferramentas Kennedy\" align=\"right\" \/><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 42224528052107467BRL108.90108.90118895BRL109321<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 108.90 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42224528052&#038;a=690303&#038;m=118895\" target=\"_blank\" rel=\"sponsored\">Loja do Mecanico BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":683539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/img.lojadomecanico.com.br\/IMAGENS\/2\/366\/107467\/Soquete-de-Impacto-Sextavado-de-34-Pol-c-gedore-200511.JPG","fifu_image_alt":"","footnotes":""},"categories":[2],"tags":[14334,40],"class_list":["post-683536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produtos","tag-108-90","tag-loja-do-mecanico-br","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts\/683536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/comments?post=683536"}],"version-history":[{"count":0,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts\/683536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/media\/683539"}],"wp:attachment":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/media?parent=683536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/categories?post=683536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/tags?post=683536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}