{"id":695300,"date":"2026-04-23T19:57:09","date_gmt":"2026-04-23T19:57:09","guid":{"rendered":"https:\/\/truckbrasil.net\/wp\/truck\/2026\/04\/23\/chave-canhao-cr-v-516-pol-x-125-mm-tramontina-pro-44261005-42224534019\/"},"modified":"2026-04-23T19:57:09","modified_gmt":"2026-04-23T19:57:09","slug":"chave-canhao-cr-v-516-pol-x-125-mm-tramontina-pro-44261005-42224534019","status":"publish","type":"post","link":"https:\/\/truckbrasil.net\/wp\/truck\/2026\/04\/23\/chave-canhao-cr-v-516-pol-x-125-mm-tramontina-pro-44261005-42224534019\/","title":{"rendered":"Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005 &#8211; 42224534019"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005 no dia da inclus\u00e3o deste produto era de <strong>R$ 22.45<\/strong>.<\/h3>\n<p><\/p>\n<p>Acesse a loja e veja se o pre\u00e7o ou estoque mudaram: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42224534019&#038;a=690303&#038;m=118895\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/ui.awin.com\/images\/upload\/merchant\/profile\/118895.png?ssl=1\" alt=\"Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005\" \/> &#8211; Loja do Mecanico BR<\/a><\/p>\n<p>Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005<\/p>\n<h5>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h5>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i3.wp.com\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png?ssl=1\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; Clique <\/a>.<\/p>\n<hr \/>\n<hr \/>\n<h4>A loja Ferramentas Kennedy oferece a possibilidade de busca mais ampla para <a href=\"https:\/\/www.ferramentaskennedy.com.br\/busca?q=Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005&#038;utm_campaign=ecompare&#038;utm_medium=maisplataforma&#038;utm_source=mais\" target=\"_blank\" rel=\"noopener\">Chave Canhao Cr-V 516 Pol x 125 mm TRAMONTINA PRO-44261005, clique e continue <strong>pesquisando&#8230;<\/strong><\/h4>\n<p><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1&w=1600&resize=1600&ssl=1 1600w\" fifu-data-src=\"https:\/\/i1.wp.com\/bucket-seed.s3.us-east-2.amazonaws.com\/ferramentaskennedy.com.br\/network\/share.png?ssl=1\" alt=\"Pesquise na Ferramentas Kennedy\" align=\"right\" \/><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 42224534019124437BRL22.4522.45118895BRL109321<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 22.45 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42224534019&#038;a=690303&#038;m=118895\" target=\"_blank\" rel=\"sponsored\">Loja do Mecanico BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":695303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/img.lojadomecanico.com.br\/IMAGENS\/2\/123\/124437\/Chave-Canhao-Cr-V-516-Pol-x-125-mm-tramontina-pro-442610051.JPG","fifu_image_alt":"","footnotes":""},"categories":[2],"tags":[14531,40],"class_list":["post-695300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produtos","tag-22-45","tag-loja-do-mecanico-br","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts\/695300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/comments?post=695300"}],"version-history":[{"count":0,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/posts\/695300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/media\/695303"}],"wp:attachment":[{"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/media?parent=695300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/categories?post=695300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truckbrasil.net\/wp\/wp-json\/wp\/v2\/tags?post=695300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}